{"id":18079,"date":"2026-08-12T13:33:41","date_gmt":"2026-08-12T11:33:41","guid":{"rendered":"https:\/\/asfdecor.com\/?post_type=product&#038;p=18079"},"modified":"2026-08-12T14:52:34","modified_gmt":"2026-08-12T12:52:34","slug":"kit-de-vinilos-sea-doo-gtx-pro-1824-inferno-vector-edition","status":"publish","type":"product","link":"https:\/\/asfdecor.com\/en\/product\/kit-de-vinilos-sea-doo-gtx-pro-1824-inferno-vector-edition\/","title":{"rendered":"Kit de vinilos Sea-Doo GTX PRO (2018-2024) Inferno Vector Edition"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Kit de vinilos compatible con <strong>Sea-Doo GTX PRO\/X 300<\/strong> (<strong>2018-2024<\/strong>), dise\u00f1ado para ofrecer una est\u00e9tica deportiva y agresiva mediante formas angulares y una combinaci\u00f3n de tonos negro, gris y naranja que realzan las l\u00edneas de la moto de agua. La exclusiva <strong>Inferno Vector Edition<\/strong> est\u00e1 fabricada por ASFDECOR con impresi\u00f3n HD sobre vinilo profesional y laminado protector de alta resistencia.<\/p>","protected":false},"featured_media":17716,"template":"","meta":[],"product_brand":[],"product_cat":[107,71,73],"product_tag":[],"class_list":["post-18079","product","type-product","status-publish","has-post-thumbnail","product_cat-gtx-pro","product_cat-motos-de-agua","product_cat-seadoo","tm-has-options","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/asfdecor.com\/en\/wp-json\/wp\/v2\/product\/18079","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/asfdecor.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/asfdecor.com\/en\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":1,"href":"https:\/\/asfdecor.com\/en\/wp-json\/wp\/v2\/product\/18079\/revisions"}],"predecessor-version":[{"id":18080,"href":"https:\/\/asfdecor.com\/en\/wp-json\/wp\/v2\/product\/18079\/revisions\/18080"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/asfdecor.com\/en\/wp-json\/wp\/v2\/media\/17716"}],"wp:attachment":[{"href":"https:\/\/asfdecor.com\/en\/wp-json\/wp\/v2\/media?parent=18079"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/asfdecor.com\/en\/wp-json\/wp\/v2\/product_brand?post=18079"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/asfdecor.com\/en\/wp-json\/wp\/v2\/product_cat?post=18079"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/asfdecor.com\/en\/wp-json\/wp\/v2\/product_tag?post=18079"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}